{"id":9435,"date":"-0001-11-30T00:00:00","date_gmt":"-0001-11-29T23:50:39","guid":{"rendered":""},"modified":"2026-05-11T07:44:54","modified_gmt":"2026-05-11T05:44:54","slug":"visite-guidee-cordes-lessenciel-7762782","status":"publish","type":"fiche_sit","link":"https:\/\/causses-gorgesaveyron.com\/en\/fiche-sit\/visite-guidee-cordes-lessenciel-7762782\/","title":{"rendered":"Visite guid\u00e9e &#8220;Cordes, l&#8217;essen&#8217;ciel&#8221;"},"content":{"rendered":"<p>V\u00e9ritable joyau m\u00e9di\u00e9val \u00e0 la beaut\u00e9 intemporelle, cette cit\u00e9 fond\u00e9e en 1222 par le comte de Toulouse exerce une fascination constante sur les visiteurs et les cr\u00e9ateurs.<br \/>\nL&#8217;AGIT vous propose 3 dates pour la d\u00e9couvrir lors des longs week-ends de mai !<\/p>","protected":false},"excerpt":{"rendered":"<p>V\u00e9ritable joyau m\u00e9di\u00e9val \u00e0 la beaut\u00e9 intemporelle, cette cit\u00e9 fond\u00e9e en 1222 par le comte de Toulouse exerce une fascination constante sur les visiteurs et les cr\u00e9ateurs. L&#8217;AGIT vous propose 3 dates pour la d\u00e9couvrir lors des longs week-ends de mai !<\/p>","protected":false},"featured_media":0,"template":"","rubrique_sit_primaire":[36,52,82],"class_list":["post-9435","fiche_sit","type-fiche_sit","status-publish","hentry","rubrique_sit_primaire-agenda","rubrique_sit_primaire-agenda-home-page","rubrique_sit_primaire-agenda-home-page-2"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/causses-gorgesaveyron.com\/en\/wp-json\/wp\/v2\/fiche_sit\/9435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/causses-gorgesaveyron.com\/en\/wp-json\/wp\/v2\/fiche_sit"}],"about":[{"href":"https:\/\/causses-gorgesaveyron.com\/en\/wp-json\/wp\/v2\/types\/fiche_sit"}],"wp:attachment":[{"href":"https:\/\/causses-gorgesaveyron.com\/en\/wp-json\/wp\/v2\/media?parent=9435"}],"wp:term":[{"taxonomy":"rubrique_sit_primaire","embeddable":true,"href":"https:\/\/causses-gorgesaveyron.com\/en\/wp-json\/wp\/v2\/rubrique_sit_primaire?post=9435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}