{"id":8791,"date":"-0001-11-30T00:00:00","date_gmt":"-0001-11-29T23:50:39","guid":{"rendered":""},"modified":"2026-04-29T12:18:04","modified_gmt":"2026-04-29T10:18:04","slug":"visites-theatralisees-6953938","status":"publish","type":"fiche_sit","link":"https:\/\/causses-gorgesaveyron.com\/es\/fiche-sit\/visites-theatralisees-6953938\/","title":{"rendered":"Visite th\u00e9\u00e2tralis\u00e9e &#8220;Les eaux troubl\u00e9es de Saint-Antonin&#8221;"},"content":{"rendered":"<p>1464, Ysabel Alibert vient d\u2019\u00eatre \u00e9lue consule, un honneur pour cette prestigieuse marchande de Saint-Antonin. Sa premi\u00e8re action ? Mettre hors d\u2019\u00e9tat de nuire Blanche Costes, une tanneuse de la ville, qui semble avoir pollu\u00e9 les eaux volontairement.<\/p>","protected":false},"excerpt":{"rendered":"<p>1464, Ysabel Alibert vient d\u2019\u00eatre \u00e9lue consule, un honneur pour cette prestigieuse marchande de Saint-Antonin. Sa premi\u00e8re action ? Mettre hors d\u2019\u00e9tat de nuire Blanche Costes, une tanneuse de la ville, qui semble avoir pollu\u00e9 les eaux volontairement.<\/p>","protected":false},"featured_media":0,"template":"","rubrique_sit_primaire":[36,52,82],"class_list":["post-8791","fiche_sit","type-fiche_sit","status-publish","hentry","rubrique_sit_primaire-agenda","rubrique_sit_primaire-agenda-home-page","rubrique_sit_primaire-agenda-home-page-2"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/causses-gorgesaveyron.com\/es\/wp-json\/wp\/v2\/fiche_sit\/8791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/causses-gorgesaveyron.com\/es\/wp-json\/wp\/v2\/fiche_sit"}],"about":[{"href":"https:\/\/causses-gorgesaveyron.com\/es\/wp-json\/wp\/v2\/types\/fiche_sit"}],"wp:attachment":[{"href":"https:\/\/causses-gorgesaveyron.com\/es\/wp-json\/wp\/v2\/media?parent=8791"}],"wp:term":[{"taxonomy":"rubrique_sit_primaire","embeddable":true,"href":"https:\/\/causses-gorgesaveyron.com\/es\/wp-json\/wp\/v2\/rubrique_sit_primaire?post=8791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}