{"id":2555,"date":"-0001-11-30T00:00:00","date_gmt":"-0001-11-29T23:50:39","guid":{"rendered":""},"modified":"2025-09-24T12:01:02","modified_gmt":"2025-09-24T10:01:02","slug":"aire-de-pique-nique-sur-les-berges-du-viaur-5822563","status":"publish","type":"fiche_sit","link":"https:\/\/causses-gorgesaveyron.com\/nl\/fiche-sit\/aire-de-pique-nique-sur-les-berges-du-viaur-5822563\/","title":{"rendered":"Aire de pique-nique sur les Berges du Viaur"},"content":{"rendered":"<p>Venez d\u00e9couvrir la tr\u00e8s belle aire de pique nique des berges du Viaur \u00e0 Lagu\u00e9pie.<\/p>","protected":false},"excerpt":{"rendered":"<p>Venez d\u00e9couvrir la tr\u00e8s belle aire de pique nique des berges du Viaur \u00e0 Lagu\u00e9pie.<\/p>","protected":false},"featured_media":0,"template":"","rubrique_sit_primaire":[34],"class_list":["post-2555","fiche_sit","type-fiche_sit","status-publish","hentry","rubrique_sit_primaire-les-aires-de-pique-nique"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/fiche_sit\/2555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/fiche_sit"}],"about":[{"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/types\/fiche_sit"}],"wp:attachment":[{"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/media?parent=2555"}],"wp:term":[{"taxonomy":"rubrique_sit_primaire","embeddable":true,"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/rubrique_sit_primaire?post=2555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}