{"id":2588,"date":"-0001-11-30T00:00:00","date_gmt":"-0001-11-29T23:50:39","guid":{"rendered":""},"modified":"2026-07-29T12:29:13","modified_gmt":"2026-07-29T10:29:13","slug":"chapelle-st-symphorien-5822814","status":"publish","type":"fiche_sit","link":"https:\/\/causses-gorgesaveyron.com\/nl\/fiche-sit\/chapelle-st-symphorien-5822814\/","title":{"rendered":"Chapelle St Symphorien"},"content":{"rendered":"<p>L\u2019\u00e9glise Saint-Symphorien, fond\u00e9e en 1011, se niche dans la vall\u00e9e de la Si\u00e9tges. Ce prieur\u00e9 du XVe si\u00e8cle, avec sa fontaine miraculeuse, est entretenu par l&#8217;association La Symphorine. Visite sur rendez-vous ou lors des Journ\u00e9es du Patrimoine.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9glise Saint-Symphorien, fond\u00e9e en 1011, se niche dans la vall\u00e9e de la Si\u00e9tges. Ce prieur\u00e9 du XVe si\u00e8cle, avec sa fontaine miraculeuse, est entretenu par l&#8217;association La Symphorine. Visite sur rendez-vous ou lors des Journ\u00e9es du Patrimoine.<\/p>","protected":false},"featured_media":0,"template":"","rubrique_sit_primaire":[35],"class_list":["post-2588","fiche_sit","type-fiche_sit","status-publish","hentry","rubrique_sit_primaire-sites-culturels"],"_links":{"self":[{"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/fiche_sit\/2588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/fiche_sit"}],"about":[{"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/types\/fiche_sit"}],"wp:attachment":[{"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/media?parent=2588"}],"wp:term":[{"taxonomy":"rubrique_sit_primaire","embeddable":true,"href":"https:\/\/causses-gorgesaveyron.com\/nl\/wp-json\/wp\/v2\/rubrique_sit_primaire?post=2588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}